{"id":243084,"date":"2021-09-27T10:58:16","date_gmt":"2021-09-27T08:58:16","guid":{"rendered":"https:\/\/affilella.es\/agenda-2030\/"},"modified":"2022-07-05T14:50:53","modified_gmt":"2022-07-05T12:50:53","slug":"agenda-2030","status":"publish","type":"page","link":"https:\/\/www.affilella.com\/fr\/agenda-2030\/","title":{"rendered":"Agenda 2030"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.6.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb use_background_color_gradient=\u00a0\u00bbon\u00a0\u00bb background_color_gradient_start=\u00a0\u00bb#009900&Prime; background_color_gradient_end=\u00a0\u00bb#115A22&Prime; background_color_gradient_direction=\u00a0\u00bb90deg\u00a0\u00bb background_color_gradient_end_position=\u00a0\u00bb40%\u00a0\u00bb custom_padding=\u00a0\u00bb40px||0px||false|false\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.6.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb0px|||||\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.6.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.6.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbLato||||||||\u00a0\u00bb height=\u00a0\u00bb120px\u00a0\u00bb max_height=\u00a0\u00bb120px\u00a0\u00bb custom_margin=\u00a0\u00bb0px|||||\u00a0\u00bb custom_padding=\u00a0\u00bb40px||0px||false|false\u00a0\u00bb]<\/p>\n<h1 style=\"font-size: 34px; text-align: center; color: white;\">Affilella s&rsquo;engage dans l&rsquo;Agenda 2030 pour le d\u00e9veloppement durable<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.6.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb3px|||||\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbLato||||||||\u00a0\u00bb]<\/p>\n<h2 style=\"text-align: center;\"><fontsninja-text id=\"fontsninja-text-151\" class=\"fontsninja-family-2048\">Nous nous engageons pour la durabilit\u00e9<\/fontsninja-text><\/h2>\n<p>[\/et_pb_text][et_pb_video src=\u00a0\u00bbhttps:\/\/www.youtube.com\/watch?v=uqDuB5UMB0c&#038;list=PL5zZPQiIP7uV0nRidbeNKfHjHD-ZmEXT8&#038;index=3&Prime; _builder_version=\u00a0\u00bb4.6.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][\/et_pb_video][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbLato||||||||\u00a0\u00bb]<\/p>\n<h3><fontsninja-text id=\"fontsninja-text-157\" class=\"fontsninja-family-2048\">Un engagement envers <span>le<\/span><\/fontsninja-text> <strong><fontsninja-text id=\"fontsninja-text-158\" class=\"fontsninja-family-2048\">d\u00e9veloppemen<span>t<\/span><\/fontsninja-text><\/strong> <fontsninja-text id=\"fontsninja-text-157\" class=\"fontsninja-family-2048\">durable est essentiel pour toutes les organisations, qu&rsquo;elles soient grandes ou petites.<\/fontsninja-text><\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.6.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<p><fontsninja-text id=\"fontsninja-text-160\" class=\"fontsninja-family-2048\">La durabilit\u00e9 offre la possibilit\u00e9 de concevoir et de mettre en \u0153uvre des strat\u00e9gies qui r\u00e9pondent \u00e0 de multiples objectifs et r\u00e9duisent les co\u00fbts globaux.<\/fontsninja-text><\/p>\n<p><strong><fontsninja-text id=\"fontsninja-text-162\" class=\"fontsninja-family-2048\">Affilell<span>a<\/span><\/fontsninja-text><\/strong> <fontsninja-text id=\"fontsninja-text-161\" class=\"fontsninja-family-2048\">croit fermement que chacun a une responsabilit\u00e9 \u00e9cologique, sociale et \u00e9conomique.<\/fontsninja-text><\/p>\n<p><fontsninja-text id=\"fontsninja-text-163\" class=\"fontsninja-family-2048\">Pour \u00eatre une entreprise durable, nous travaillons dur sur des projets de d\u00e9veloppement durable innovants, afin de minimiser l&rsquo;impact environnemental et de r\u00e9duire les d\u00e9chets.<\/fontsninja-text><\/p>\n<p><fontsninja-text id=\"fontsninja-text-164\" class=\"fontsninja-family-2048\">Dans cette <span>optique<\/span><\/fontsninja-text>, <strong><fontsninja-text id=\"fontsninja-text-166\" class=\"fontsninja-family-2049\">Affilella<\/fontsninja-text><\/strong> <fontsninja-text id=\"fontsninja-text-164\" class=\"fontsninja-family-2048\">a d\u00e9cid\u00e9 de <span>rejoindre<\/span><\/fontsninja-text> \u201c<strong><a href=\"https:\/\/www.un.org\/sustainabledevelopment\/fr\/development-agenda\/\" target=\"_blank\" rel=\"noopener noreferrer\"><fontsninja-text id=\"fontsninja-text-167\" class=\"fontsninja-family-2048\">2030 Agenda pour le d\u00e9veloppement durable<\/fontsninja-text><\/a><\/strong>\u201d <fontsninja-text id=\"fontsninja-text-164\" class=\"fontsninja-family-2048\"><span>qui<\/span> a d\u00e9fini une s\u00e9rie de 17 objectifs de d\u00e9veloppement durable (ODD) qui nous concernent tous.<\/fontsninja-text><\/p>\n<p><fontsninja-text id=\"fontsninja-text-168\" class=\"fontsninja-family-2048\">Certains des objectifs sont pour l&rsquo;environnement, certains pour le d\u00e9veloppement \u00e9conomique et les questions sociales, certains pour la sant\u00e9 et certains pour la paix et la s\u00e9curit\u00e9. Tous ces objectifs sont tr\u00e8s ambitieux et nous obligent \u00e0 apporter des changements dans notre vie et dans le monde qui nous entoure.<\/fontsninja-text><\/p>\n<p><fontsninja-text id=\"fontsninja-text-169\" class=\"fontsninja-family-2048\">La durabilit\u00e9 est un choix \u00e9thique et le point de d\u00e9part est la volont\u00e9 de cr\u00e9er de la valeur \u00e0 moyen et long terme.<\/fontsninja-text><\/p>\n<p><fontsninja-text id=\"fontsninja-text-170\" class=\"fontsninja-family-2048\">Notre organisation est donc motiv\u00e9e \u00e0 participer \u00e0 cet engagement global en promouvant une s\u00e9rie d&rsquo;actions concr\u00e8tes sur le terrain.<\/fontsninja-text><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb border_width_top=\u00a0\u00bb1px\u00a0\u00bb border_color_top=\u00a0\u00bbrgba(0,0,0,0.18)\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbLato||||||||\u00a0\u00bb header_2_text_align=\u00a0\u00bbcenter\u00a0\u00bb custom_padding=\u00a0\u00bb23px||23px||true|false\u00a0\u00bb border_color_top=\u00a0\u00bbrgba(0,0,0,0.17)\u00a0\u00bb border_color_bottom=\u00a0\u00bbrgba(0,0,0,0.17)\u00a0\u00bb]<\/p>\n<h2 style=\"text-align: center;\"><fontsninja-text id=\"fontsninja-text-174\" class=\"fontsninja-family-2048\">Comment notre entreprise peut contribuer \u00e0 cette discussion<\/fontsninja-text><\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb]<\/p>\n<p><fontsninja-text id=\"fontsninja-text-175\" class=\"fontsninja-family-2048\">Nous avons des plans d&rsquo;action simples mais tr\u00e8s efficaces qui donnent des r\u00e9sultats imm\u00e9diats et \u00e0 long terme. Nous travaillons ainsi pour atteindre des objectifs de durabilit\u00e9 et pour savoir que nos actions auront un impact direct sur la vie de l&rsquo;autre.<\/fontsninja-text><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb2_3,1_3&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb border_width_top=\u00a0\u00bb1px\u00a0\u00bb border_color_top=\u00a0\u00bbrgba(0,0,0,0.17)\u00a0\u00bb border_width_bottom=\u00a0\u00bb1px\u00a0\u00bb border_color_bottom=\u00a0\u00bbrgba(0,0,0,0.17)\u00a0\u00bb][et_pb_column type=\u00a0\u00bb2_3&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_4_text_color=\u00a0\u00bb#4c9f38&Prime; header_4_font_size=\u00a0\u00bb21px\u00a0\u00bb]<\/p>\n<h4><strong><fontsninja-text id=\"fontsninja-text-182\" class=\"fontsninja-family-2048\">\u00ab\u00a0Donner aux individus les moyens de vivre une vie saine et promouvoir le bien-\u00eatre \u00e0 tous les \u00e2ges\u00a0\u00bb<\/fontsninja-text><\/strong><\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb]<\/p>\n<p><fontsninja-text id=\"fontsninja-text-183\" class=\"fontsninja-family-2048\">Tous les employ\u00e9s sont soumis \u00e0 des examens m\u00e9dicaux pr\u00e9ventifs et p\u00e9riodiques pour le travail.<\/fontsninja-text><\/p>\n<p><fontsninja-text id=\"fontsninja-text-185\" class=\"fontsninja-family-2048\">Par ailleurs, le Groupe a mis en place une Caisse Compl\u00e9mentaire de Sant\u00e9 &#8211; CADIPROF (https:\/\/www.cadiprof.it\/) et a d\u00e9j\u00e0 pris des mesures pour mettre \u00e0 disposition des employ\u00e9s:<\/fontsninja-text><\/p>\n<ul>\n<li><fontsninja-text id=\"fontsninja-text-187\" class=\"fontsninja-family-2048\">Vaccins contre la grippe<\/fontsninja-text><\/li>\n<li><fontsninja-text id=\"fontsninja-text-188\" class=\"fontsninja-family-2048\">Covid-19 tests s\u00e9rologiques<\/fontsninja-text><\/li>\n<li><fontsninja-text id=\"fontsninja-text-189\" class=\"fontsninja-family-2048\">Covid-19 tampons salivaire<\/fontsninja-text><\/li>\n<li><fontsninja-text id=\"fontsninja-text-190\" class=\"fontsninja-family-2048\">Covid-19 vaccins<\/fontsninja-text><\/li>\n<\/ul>\n<p><strong><fontsninja-text id=\"fontsninja-text-192\" class=\"fontsninja-family-2048\">CE QUE NOUS SOMMES ENGAG\u00c9S \u00c0 FAIRE<\/fontsninja-text><\/strong><\/p>\n<p><fontsninja-text id=\"fontsninja-text-193\" class=\"fontsninja-family-2048\">Des kits d&rsquo;autotest seront mis \u00e0 disposition des employ\u00e9s pour effectuer des d\u00e9pistages p\u00e9riodiques (glyc\u00e9mie, cholest\u00e9rol, etc.)<\/fontsninja-text><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/affilella.es\/wp-content\/uploads\/2021\/09\/03-bonne-sante-bien-etre.jpg\u00a0\u00bb alt=\u00a0\u00bbAgenda 2030 &#8211; sant\u00e9 et bien-\u00eatre\u00a0\u00bb title_text=\u00a0\u00bb03-bonne-sante-bien-etre\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.6.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb2_3,1_3&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb border_width_top=\u00a0\u00bb1px\u00a0\u00bb border_color_top=\u00a0\u00bbrgba(0,0,0,0.17)\u00a0\u00bb border_width_bottom=\u00a0\u00bb1px\u00a0\u00bb border_color_bottom=\u00a0\u00bbrgba(0,0,0,0.17)\u00a0\u00bb][et_pb_column type=\u00a0\u00bb2_3&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_main_element=\u00a0\u00bbmargin:auto;\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#c4182e\u00a0\u00bb header_4_text_color=\u00a0\u00bb#c4182e\u00a0\u00bb header_4_font_size=\u00a0\u00bb21px\u00a0\u00bb]<\/p>\n<h4><strong>\u00ab\u00a0Veiller \u00e0 ce que tous puissent suivre une \u00e9ducation de qualit\u00e9 dans des conditions d\u2019\u00e9quit\u00e9 et promouvoir les possibilit\u00e9s d\u2019apprentissage tout au long de la vie.\u00a0\u00bb<\/strong><\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb]<\/p>\n<p><strong>CE QUE NOUS SOMMES ENGAG\u00c9S \u00c0 FAIRE<\/strong><\/p>\n<p>A partir de septembre 2021, des cours en pr\u00e9sentiel seront organis\u00e9s pour les employ\u00e9s (au si\u00e8ge de Carpi), qui seront stream\u00e9s et rendus accessibles \u00e0 tous en mode e-learning, m\u00eame apr\u00e8s l&rsquo;\u00e9v\u00e9nement. Quelques exemples:<\/p>\n<ul>\n<li>Cours Excel de base et interm\u00e9diaire;<\/li>\n<li>Cours d&rsquo;anglais de base et interm\u00e9diaire pour les travailleurs;<\/li>\n<li>Cours de guide \u00e0 la lecture de la fiche de paie;<\/li>\n<li>Journ\u00e9e avec la nutritionniste.<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/affilella.es\/wp-content\/uploads\/2021\/09\/04-education-de-qualite.jpg\u00a0\u00bb alt=\u00a0\u00bbAgenda 2030 &#8211; \u00e9ducation de qualit\u00e9\u00a0\u00bb title_text=\u00a0\u00bb04-education-de-qualite\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.6.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb2_3,1_3&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb border_width_top=\u00a0\u00bb1px\u00a0\u00bb border_color_top=\u00a0\u00bbrgba(0,0,0,0.17)\u00a0\u00bb border_width_bottom=\u00a0\u00bb1px\u00a0\u00bb border_color_bottom=\u00a0\u00bbrgba(0,0,0,0.17)\u00a0\u00bb][et_pb_column type=\u00a0\u00bb2_3&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_main_element=\u00a0\u00bbmargin:auto;\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.6.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#c4182e\u00a0\u00bb header_4_text_color=\u00a0\u00bb#ff3a20&Prime; header_4_font_size=\u00a0\u00bb21px\u00a0\u00bb]<\/p>\n<h4><span style=\"color: #ffcc00;\"><strong>\u00ab\u00a0<\/strong><strong>Garantir l\u2019acc\u00e8s de tous \u00e0 des services \u00e9nerg\u00e9tiques fiables, durables et modernes, \u00e0 un co\u00fbt abordable.\u00a0\u00bb<\/strong><\/span><\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.6.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb]<span>Affilella s&rsquo;engage \u00e0 respecter l&rsquo;environnement, dans une optique d&rsquo;efficacit\u00e9 \u00e9lev\u00e9e avec un faible impact environnemental pour l&rsquo;ensemble du processus de production: de l&rsquo;approvisionnement \u00e0 la production, de l&rsquo;utilisation \u00e0 l&rsquo;\u00e9limination.<\/span><\/p>\n<p><strong>CE QUE NOUS SOMMES ENGAG\u00c9S \u00c0 FAIRE<\/strong><\/p>\n<ul>\n<li class=\"\">Nous utilisons des syst\u00e8mes photovolta\u00efques qui utilisent l&rsquo;\u00e9nergie solaire pour produire de l&rsquo;\u00e9lectricit\u00e9, r\u00e9duisant consid\u00e9rablement les \u00e9missions de CO2;<\/li>\n<li class=\"\">Nous utilisons des peintures \u00e0 l&rsquo;eau qui n&rsquo;ont pas besoin d&rsquo;\u00eatre dilu\u00e9es dans des solvants chimiques et par cons\u00e9quent ne polluent pas;<\/li>\n<li class=\"\">Nous utilisons des syst\u00e8mes de filtration pour am\u00e9liorer la qualit\u00e9 de l&rsquo;air dans les locaux;<\/li>\n<li class=\"\">Nous utilisons des purificateurs sp\u00e9ciaux pour assurer l&rsquo;\u00e9limination des \u00e9l\u00e9ments polluants de l&rsquo;eau, les rendant ainsi jetables ou r\u00e9utilisables;<\/li>\n<li class=\"\">Nous installons des composants qui n\u00e9cessitent peu d&rsquo;\u00e9lectricit\u00e9 pour leur fonctionnement tels que des mandrins \u00e9lectromagn\u00e9tiques permanents, des moteurs \u00e0 haut rendement et des onduleurs qui modulent la puissance des moteurs.<\/li>\n<\/ul>\n<ul><\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/affilella.es\/wp-content\/uploads\/2021\/09\/07-energie-propre-cout-abordable.jpg\u00a0\u00bb alt=\u00a0\u00bbAgenda 2030 &#8211; \u00e9galit\u00e9 des sexes\u00a0\u00bb title_text=\u00a0\u00bb07-energie-propre-cout-abordable\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.6.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb2_3,1_3&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb border_width_top=\u00a0\u00bb1px\u00a0\u00bb border_color_top=\u00a0\u00bbrgba(0,0,0,0.17)\u00a0\u00bb border_width_bottom=\u00a0\u00bb1px\u00a0\u00bb border_color_bottom=\u00a0\u00bbrgba(0,0,0,0.17)\u00a0\u00bb][et_pb_column type=\u00a0\u00bb2_3&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_main_element=\u00a0\u00bbmargin:auto;\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#c4182e\u00a0\u00bb header_4_text_color=\u00a0\u00bb#fd9d24&Prime; header_4_font_size=\u00a0\u00bb21px\u00a0\u00bb]<\/p>\n<h4><\/h4>\n<h4><strong>\u00ab\u00a0<\/strong><strong>Faire en sorte que les villes et les \u00e9tablissements humains soient ouverts \u00e0 tous, s\u00fbrs, r\u00e9silients et durables.<\/strong><strong>\u00ab\u00a0<\/strong><\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.6.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb]<\/p>\n<p><strong>CE QUE NOUS SOMMES ENGAG\u00c9S \u00c0 FAIRE<\/strong><\/p>\n<ul>\n<li>Renforcer les efforts de protection et de sauvegarde du patrimoine culturel et naturel mondial.<\/li>\n<li>R\u00e9duire l&rsquo;impact environnemental n\u00e9gatif par habitant en portant une attention particuli\u00e8re \u00e0 la gestion des d\u00e9chets.<\/li>\n<\/ul>\n<ul><\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/affilella.es\/wp-content\/uploads\/2021\/09\/11-vills-et-communautes-durables.jpg\u00a0\u00bb alt=\u00a0\u00bbAgenda 2030 &#8211; \u00e9ducation de qualit\u00e9\u00a0\u00bb title_text=\u00a0\u00bb11-vills-et-communautes-durables\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb align_tablet=\u00a0\u00bb\u00a0\u00bb align_phone=\u00a0\u00bb\u00a0\u00bb align_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb _builder_version=\u00a0\u00bb4.6.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb2_3,1_3&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb border_width_top=\u00a0\u00bb1px\u00a0\u00bb border_color_top=\u00a0\u00bbrgba(0,0,0,0.17)\u00a0\u00bb border_width_bottom=\u00a0\u00bb1px\u00a0\u00bb border_color_bottom=\u00a0\u00bbrgba(0,0,0,0.17)\u00a0\u00bb][et_pb_column type=\u00a0\u00bb2_3&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_main_element=\u00a0\u00bbmargin:auto;\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#c4182e\u00a0\u00bb header_4_text_color=\u00a0\u00bb#c08b2f\u00a0\u00bb header_4_font_size=\u00a0\u00bb21px\u00a0\u00bb]<\/p>\n<h4><\/h4>\n<h4><strong>\u00ab\u00a0<\/strong><strong><\/strong><strong>\u00c9tablir des modes de consommation et de production durables.<\/strong> <strong><\/strong><strong>\u00ab\u00a0<\/strong><\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.6.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb]<\/p>\n<p><strong>CE QUE NOUS SOMMES ENGAG\u00c9S \u00c0 FAIRE<\/strong><\/p>\n<ul>\n<li>R\u00e9duire consid\u00e9rablement la production de d\u00e9chets par la pr\u00e9vention, la r\u00e9duction, le recyclage et la r\u00e9utilisation;<\/li>\n<li>R\u00e9duire l&rsquo;impact environnemental n\u00e9gatif par habitant en portant une attention particuli\u00e8re \u00e0 la gestion des d\u00e9chets;<\/li>\n<li>Mettre en place une proc\u00e9dure interne pour limiter l&rsquo;impression en g\u00e9n\u00e9ral, avec l&rsquo;interdiction de l&rsquo;impression couleur (sinon strictement indispensable), l&rsquo;obligation de faire des impressions recto-verso et l&rsquo;obligation de r\u00e9utiliser les feuilles imprim\u00e9es sur une seule face;<\/li>\n<li>Parvenir \u00e0 une gestion \u00e9cologique des produits chimiques et de tous les d\u00e9chets tout au long de leur cycle de vie, conform\u00e9ment aux cadres internationaux convenus, et r\u00e9duire consid\u00e9rablement leur rejet dans l&rsquo;air, l&rsquo;eau et le sol pour minimiser leur impact n\u00e9gatif sur la sant\u00e9 des \u00eatres humains et l&rsquo;environnement.<\/li>\n<\/ul>\n<ul><\/ul>\n<ul><\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/affilella.es\/wp-content\/uploads\/2021\/09\/12-consommation-et-production-responsables.jpg\u00a0\u00bb alt=\u00a0\u00bbAgenda 2030 &#8211; \u00e9ducation de qualit\u00e9\u00a0\u00bb title_text=\u00a0\u00bb12-consommation-et-production-responsables\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb align_tablet=\u00a0\u00bb\u00a0\u00bb align_phone=\u00a0\u00bb\u00a0\u00bb align_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb _builder_version=\u00a0\u00bb4.6.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb2_3,1_3&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb border_width_top=\u00a0\u00bb1px\u00a0\u00bb border_color_top=\u00a0\u00bbrgba(0,0,0,0.17)\u00a0\u00bb border_width_bottom=\u00a0\u00bb1px\u00a0\u00bb border_color_bottom=\u00a0\u00bbrgba(0,0,0,0.17)\u00a0\u00bb][et_pb_column type=\u00a0\u00bb2_3&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_main_element=\u00a0\u00bbmargin:auto;\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#c4182e\u00a0\u00bb header_4_text_color=\u00a0\u00bb#9abd9a\u00a0\u00bb header_4_font_size=\u00a0\u00bb21px\u00a0\u00bb]<\/p>\n<h4><strong>\u00ab\u00a0<\/strong><strong>Prendre d\u2019urgence des mesures pour lutter contre les changements climatiques et leurs r\u00e9percussions<\/strong><strong><\/strong><strong>\u00ab\u00a0<\/strong><\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.6.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb]<\/p>\n<p><strong>CE QUE NOUS SOMMES ENGAG\u00c9S \u00c0 FAIRE<\/strong><\/p>\n<ul>\n<ul>\n<li>Activer les proc\u00e9dures internes pour minimiser l&rsquo;utilisation du papier et favoriser son recyclage;<\/li>\n<li>Limitez les impressions au minimum, en incluant l&rsquo;invitation \u00ab Respectez l&rsquo;environnement, r\u00e9fl\u00e9chissez avant d&rsquo;imprimer cet e-mail \u00bb dans les signatures d&rsquo;e-mails;<\/li>\n<li>Promouvoir la bonne pratique de la collecte s\u00e9lective, tant dans l&rsquo;entreprise qu&rsquo;\u00e0 domicile;<\/li>\n<li>Promouvoir la r\u00e9duction de l&rsquo;utilisation du plastique et l&rsquo;\u00e9limination du plastique jetable. Concr\u00e8tement, des bouteilles d&rsquo;eau thermique en aluminium seront achet\u00e9es et attribu\u00e9es \u00e0 chaque employ\u00e9, qui seront remplies via des distributeurs\/purificateurs connect\u00e9s directement \u00e0 l&rsquo;approvisionnement en eau pour remplacer les bouteilles en plastique.<\/li>\n<li>Les distributeurs de boissons chaudes seront \u00e9quip\u00e9s de gobelets en papier et d&rsquo;agitateurs, tandis que les boissons seront distribu\u00e9es en canettes.<\/li>\n<\/ul>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/affilella.es\/wp-content\/uploads\/2021\/09\/13-mesures-relatives-lutte-contre-changements-climatiques.jpg\u00a0\u00bb alt=\u00a0\u00bbAgenda 2030 &#8211; \u00e9ducation de qualit\u00e9\u00a0\u00bb title_text=\u00a0\u00bb13-mesures-relatives-lutte-contre-changements-climatiques\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb align_tablet=\u00a0\u00bb\u00a0\u00bb align_phone=\u00a0\u00bb\u00a0\u00bb align_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb _builder_version=\u00a0\u00bb4.6.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb2_3,1_3&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb border_width_top=\u00a0\u00bb1px\u00a0\u00bb border_color_top=\u00a0\u00bbrgba(0,0,0,0.17)\u00a0\u00bb border_width_bottom=\u00a0\u00bb1px\u00a0\u00bb border_color_bottom=\u00a0\u00bbrgba(0,0,0,0.17)\u00a0\u00bb][et_pb_column type=\u00a0\u00bb2_3&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_main_element=\u00a0\u00bbmargin:auto;\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#c4182e\u00a0\u00bb header_4_text_color=\u00a0\u00bb#1a486a\u00a0\u00bb header_4_font_size=\u00a0\u00bb21px\u00a0\u00bb]<\/p>\n<h4><strong>\u00ab\u00a0<\/strong><strong>Partenariats pour la r\u00e9alisation des objectifs.<\/strong><strong><\/strong><strong>\u00ab\u00a0<\/strong><\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.6.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb]<\/p>\n<p><strong>CE QUE NOUS SOMMES ENGAG\u00c9S \u00c0 FAIRE<\/strong><\/p>\n<ul>\n<li>Intensifier et privil\u00e9gier les partenariats et collaborations avec des entreprises qui d\u00e9veloppent et partagent des connaissances, des comp\u00e9tences, des ressources technologiques et financi\u00e8res, pour atteindre les objectifs de D\u00e9veloppement Durable.<\/li>\n<li>Encourager et promouvoir des collaborations efficaces bas\u00e9es sur l&rsquo;exp\u00e9rience des partenariats et leur capacit\u00e9 \u00e0 trouver des ressources.<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/affilella.es\/wp-content\/uploads\/2021\/09\/17-partenaires-pour-realisation-des-objectigs.jpg\u00a0\u00bb alt=\u00a0\u00bbAgenda 2030 &#8211; \u00e9ducation de qualit\u00e9\u00a0\u00bb title_text=\u00a0\u00bb17-partenaires-pour-realisation-des-objectigs\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb align_tablet=\u00a0\u00bb\u00a0\u00bb align_phone=\u00a0\u00bb\u00a0\u00bb align_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb _builder_version=\u00a0\u00bb4.6.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Affilella s&rsquo;engage dans l&rsquo;Agenda 2030 pour le d\u00e9veloppement durableNous nous engageons pour la durabilit\u00e9Un engagement envers le d\u00e9veloppement durable est essentiel pour toutes les organisations, qu&rsquo;elles soient grandes ou petites.La durabilit\u00e9 offre la possibilit\u00e9 de concevoir et de mettre en \u0153uvre des strat\u00e9gies qui r\u00e9pondent \u00e0 de multiples objectifs et r\u00e9duisent les co\u00fbts globaux. Affilella croit fermement que chacun a une responsabilit\u00e9 \u00e9cologique, sociale et \u00e9conomique. Pour \u00eatre une entreprise durable, nous travaillons dur sur des projets de d\u00e9veloppement durable innovants, afin de minimiser l&rsquo;impact environnemental et de r\u00e9duire les d\u00e9chets. Dans cette optique, Affilella a d\u00e9cid\u00e9 de rejoindre \u201c2030 Agenda pour le d\u00e9veloppement durable\u201d qui a d\u00e9fini une s\u00e9rie de 17 objectifs de d\u00e9veloppement durable (ODD) qui nous concernent tous. Certains des objectifs sont pour l&rsquo;environnement, certains pour le d\u00e9veloppement \u00e9conomique et les questions sociales, certains pour la sant\u00e9 et certains pour la paix et la s\u00e9curit\u00e9. Tous ces objectifs sont tr\u00e8s ambitieux et nous obligent \u00e0 apporter des changements dans notre vie et dans le monde qui nous entoure. La durabilit\u00e9 est un choix \u00e9thique et le point de d\u00e9part est la volont\u00e9 de cr\u00e9er de la valeur \u00e0 moyen et long terme. Notre organisation est donc motiv\u00e9e [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-243084","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Agenda 2030 - Affilella<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.affilella.com\/agenda-2030\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Agenda 2030\" \/>\n<meta property=\"og:description\" content=\"Affilella s&#039;engage dans l&#039;Agenda 2030 pour le d\u00e9veloppement durableNous nous engageons pour la durabilit\u00e9Un engagement envers le d\u00e9veloppement durable est essentiel pour toutes les organisations, qu&#039;elles soient grandes ou petites.La durabilit\u00e9 offre la possibilit\u00e9 de concevoir et de mettre en \u0153uvre des strat\u00e9gies qui r\u00e9pondent \u00e0 de multiples objectifs et r\u00e9duisent les co\u00fbts globaux. Affilella croit fermement que chacun a une responsabilit\u00e9 \u00e9cologique, sociale et \u00e9conomique. Pour \u00eatre une entreprise durable, nous travaillons dur sur des projets de d\u00e9veloppement durable innovants, afin de minimiser l&#039;impact environnemental et de r\u00e9duire les d\u00e9chets. Dans cette optique, Affilella a d\u00e9cid\u00e9 de rejoindre \u201c2030 Agenda pour le d\u00e9veloppement durable\u201d qui a d\u00e9fini une s\u00e9rie de 17 objectifs de d\u00e9veloppement durable (ODD) qui nous concernent tous. Certains des objectifs sont pour l&#039;environnement, certains pour le d\u00e9veloppement \u00e9conomique et les questions sociales, certains pour la sant\u00e9 et certains pour la paix et la s\u00e9curit\u00e9. Tous ces objectifs sont tr\u00e8s ambitieux et nous obligent \u00e0 apporter des changements dans notre vie et dans le monde qui nous entoure. La durabilit\u00e9 est un choix \u00e9thique et le point de d\u00e9part est la volont\u00e9 de cr\u00e9er de la valeur \u00e0 moyen et long terme. Notre organisation est donc motiv\u00e9e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.affilella.com\/agenda-2030\/\" \/>\n<meta property=\"og:site_name\" content=\"Affilella\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/affilella\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-05T12:50:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.affilella.com\/wp-content\/uploads\/2021\/07\/affilella_dettaglio_lama.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.affilella.com\\\/agenda-2030\\\/\",\"url\":\"https:\\\/\\\/www.affilella.com\\\/agenda-2030\\\/\",\"name\":\"Agenda 2030 - Affilella\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.affilella.com\\\/#website\"},\"datePublished\":\"2021-09-27T08:58:16+00:00\",\"dateModified\":\"2022-07-05T12:50:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.affilella.com\\\/agenda-2030\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.affilella.com\\\/agenda-2030\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.affilella.com\\\/agenda-2030\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.affilella.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Agenda 2030\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.affilella.com\\\/#website\",\"url\":\"https:\\\/\\\/www.affilella.com\\\/\",\"name\":\"Affilella\",\"description\":\"Afiladora Professional\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.affilella.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Agenda 2030 - Affilella","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.affilella.com\/agenda-2030\/","og_locale":"fr_FR","og_type":"article","og_title":"Agenda 2030","og_description":"Affilella s'engage dans l'Agenda 2030 pour le d\u00e9veloppement durableNous nous engageons pour la durabilit\u00e9Un engagement envers le d\u00e9veloppement durable est essentiel pour toutes les organisations, qu'elles soient grandes ou petites.La durabilit\u00e9 offre la possibilit\u00e9 de concevoir et de mettre en \u0153uvre des strat\u00e9gies qui r\u00e9pondent \u00e0 de multiples objectifs et r\u00e9duisent les co\u00fbts globaux. Affilella croit fermement que chacun a une responsabilit\u00e9 \u00e9cologique, sociale et \u00e9conomique. Pour \u00eatre une entreprise durable, nous travaillons dur sur des projets de d\u00e9veloppement durable innovants, afin de minimiser l'impact environnemental et de r\u00e9duire les d\u00e9chets. Dans cette optique, Affilella a d\u00e9cid\u00e9 de rejoindre \u201c2030 Agenda pour le d\u00e9veloppement durable\u201d qui a d\u00e9fini une s\u00e9rie de 17 objectifs de d\u00e9veloppement durable (ODD) qui nous concernent tous. Certains des objectifs sont pour l'environnement, certains pour le d\u00e9veloppement \u00e9conomique et les questions sociales, certains pour la sant\u00e9 et certains pour la paix et la s\u00e9curit\u00e9. Tous ces objectifs sont tr\u00e8s ambitieux et nous obligent \u00e0 apporter des changements dans notre vie et dans le monde qui nous entoure. La durabilit\u00e9 est un choix \u00e9thique et le point de d\u00e9part est la volont\u00e9 de cr\u00e9er de la valeur \u00e0 moyen et long terme. Notre organisation est donc motiv\u00e9e [&hellip;]","og_url":"https:\/\/www.affilella.com\/agenda-2030\/","og_site_name":"Affilella","article_publisher":"https:\/\/www.facebook.com\/affilella","article_modified_time":"2022-07-05T12:50:53+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/www.affilella.com\/wp-content\/uploads\/2021\/07\/affilella_dettaglio_lama.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.affilella.com\/agenda-2030\/","url":"https:\/\/www.affilella.com\/agenda-2030\/","name":"Agenda 2030 - Affilella","isPartOf":{"@id":"https:\/\/www.affilella.com\/#website"},"datePublished":"2021-09-27T08:58:16+00:00","dateModified":"2022-07-05T12:50:53+00:00","breadcrumb":{"@id":"https:\/\/www.affilella.com\/agenda-2030\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.affilella.com\/agenda-2030\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.affilella.com\/agenda-2030\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.affilella.com\/"},{"@type":"ListItem","position":2,"name":"Agenda 2030"}]},{"@type":"WebSite","@id":"https:\/\/www.affilella.com\/#website","url":"https:\/\/www.affilella.com\/","name":"Affilella","description":"Afiladora Professional","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.affilella.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.affilella.com\/fr\/wp-json\/wp\/v2\/pages\/243084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.affilella.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.affilella.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.affilella.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.affilella.com\/fr\/wp-json\/wp\/v2\/comments?post=243084"}],"version-history":[{"count":4,"href":"https:\/\/www.affilella.com\/fr\/wp-json\/wp\/v2\/pages\/243084\/revisions"}],"predecessor-version":[{"id":245301,"href":"https:\/\/www.affilella.com\/fr\/wp-json\/wp\/v2\/pages\/243084\/revisions\/245301"}],"wp:attachment":[{"href":"https:\/\/www.affilella.com\/fr\/wp-json\/wp\/v2\/media?parent=243084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}